{"id":912,"date":"2023-11-29T13:19:58","date_gmt":"2023-11-29T16:19:58","guid":{"rendered":"https:\/\/cajapopular.gov.ar\/?page_id=912"},"modified":"2025-02-13T09:58:31","modified_gmt":"2025-02-13T12:58:31","slug":"accion-social","status":"publish","type":"page","link":"https:\/\/www.cajapopular.gov.ar\/index.php\/accion-social\/","title":{"rendered":"Acci\u00f3n Social"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbHero\u00bb _builder_version=\u00bb4.22.1&#8243; background_color=\u00bb#007d84&#8243; background_enable_image=\u00bboff\u00bb custom_margin=\u00bb||||false\u00bb custom_padding=\u00bb10vw||10vw||true|false\u00bb da_disable_devices=\u00bboff|off|off\u00bb global_colors_info=\u00bb{}\u00bb da_is_popup=\u00bboff\u00bb da_exit_intent=\u00bboff\u00bb da_has_close=\u00bbon\u00bb da_alt_close=\u00bboff\u00bb da_dark_close=\u00bboff\u00bb da_not_modal=\u00bbon\u00bb da_is_singular=\u00bboff\u00bb da_with_loader=\u00bboff\u00bb da_has_shadow=\u00bbon\u00bb][et_pb_row column_structure=\u00bb2_3,1_3&#8243; _builder_version=\u00bb4.22.1&#8243; border_color_all=\u00bb#ffffff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb2_3&#8243; _builder_version=\u00bb4.22.1&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.22.1&#8243; text_font=\u00bb||||||||\u00bb header_font=\u00bbRoboto|700|||||||\u00bb header_font_size=\u00bb64px\u00bb header_line_height=\u00bb1.1em\u00bb background_layout=\u00bbdark\u00bb max_width=\u00bb800px\u00bb custom_margin=\u00bb||0px|\u00bb custom_padding=\u00bb|||16px\u00bb text_font_size_tablet=\u00bb14px\u00bb text_font_size_last_edited=\u00bboff|desktop\u00bb header_font_size_tablet=\u00bb44px\u00bb header_font_size_phone=\u00bb32px\u00bb header_font_size_last_edited=\u00bbon|phone\u00bb border_color_all=\u00bb#ffffff\u00bb border_width_left=\u00bb10px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h1>Noticias<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb da_disable_devices=\u00bboff|off|off\u00bb global_colors_info=\u00bb{}\u00bb da_is_popup=\u00bboff\u00bb da_exit_intent=\u00bboff\u00bb da_has_close=\u00bbon\u00bb da_alt_close=\u00bboff\u00bb da_dark_close=\u00bboff\u00bb da_not_modal=\u00bbon\u00bb da_is_singular=\u00bboff\u00bb da_with_loader=\u00bboff\u00bb da_has_shadow=\u00bbon\u00bb][et_pb_row _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_button button_text=\u00bb \u00bb button_alignment=\u00bbright\u00bb module_id=\u00bbboton-flotante\u00bb module_class=\u00bbboton-flotante\u00bb _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb20px\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#e9530d\u00bb button_border_width=\u00bb2px\u00bb button_border_radius=\u00bb78px\u00bb button_letter_spacing=\u00bb0px\u00bb button_icon=\u00bb&#x3a;||divi||400&#8243; button_icon_color=\u00bb#ffffff\u00bb button_icon_placement=\u00bbleft\u00bb button_on_hover=\u00bboff\u00bb positioning=\u00bbfixed\u00bb z_index=\u00bb0&#8243; custom_margin=\u00bb6px|-149px|5px|-19px|false|false\u00bb custom_padding=\u00bb31px|7px|63px|38px|false|false\u00bb box_shadow_style=\u00bbpreset2&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb da_disable_devices=\u00bboff|off|off\u00bb global_colors_info=\u00bb{}\u00bb da_is_popup=\u00bboff\u00bb da_exit_intent=\u00bboff\u00bb da_has_close=\u00bbon\u00bb da_alt_close=\u00bboff\u00bb da_dark_close=\u00bboff\u00bb da_not_modal=\u00bbon\u00bb da_is_singular=\u00bboff\u00bb da_with_loader=\u00bboff\u00bb da_has_shadow=\u00bbon\u00bb][et_pb_row _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbRevalorizaci\u00f3n de sucursal en Taf\u00ed del Valle\u00bb image=\u00bbhttps:\/\/cajapopular.gov.ar\/wp-content\/uploads\/2025\/02\/sucursal-tafi-del-valle.png\u00bb content_max_width=\u00bb1100px\u00bb _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb header_font=\u00bbRoboto|700|||||||\u00bb header_text_color=\u00bb#606060&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><span>Caja Popular de Ahorros concret\u00f3 la revalorizaci\u00f3n de su sucursal en Taf\u00ed del Valle, trasladandola a una nueva ubicaci\u00f3n, en Av Belgrano 175 L101, Galer\u00eda Inti del Taf\u00ed; en el coraz\u00f3n de una de las villas veraniegas por excelencia en nuestra provincia.<\/span><\/p>\n<p><span>Con una fachada totalmente renovada, en esta sucursal se podr\u00e1n realizar tr\u00e1mites relacionados a la obtenci\u00f3n de seguros, cr\u00e9ditos, solicitud de productos comerciales como tarjetas de cr\u00e9dito, apertura de caja de ahorros, y pago de impuestos y servicios, entre otros; adem\u00e1s de poder acceder a nuestros cajeros autom\u00e1ticos.<\/span><\/p>\n<p><span>En esta ocasi\u00f3n, las autoridades presentes para la inauguraci\u00f3n de la sucursal fueron los responsables del \u00e1rea t\u00e9cnica de sucursales y delegaciones, MMO Franco Vargas; Arq. Camila Taranc\u00f3n; Ing. Jos\u00e9 Luis Leccesi; junto al Gte. Gral. de Personal; Sr. Javier D\u00edaz; y el Sub Interventor de Caja Popular de Ahorros, Sr. Dario Amatti. Adem\u00e1s, la bendici\u00f3n fue realizada por el Padre Daniel Cano.<\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; theme_builder_area=\u00bbpost_content\u00bb _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb da_is_popup=\u00bboff\u00bb da_exit_intent=\u00bboff\u00bb da_has_close=\u00bbon\u00bb da_alt_close=\u00bboff\u00bb da_dark_close=\u00bboff\u00bb da_not_modal=\u00bbon\u00bb da_is_singular=\u00bboff\u00bb da_with_loader=\u00bboff\u00bb da_has_shadow=\u00bbon\u00bb da_disable_devices=\u00bboff|off|off\u00bb][et_pb_row _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb type=\u00bb4_4&#8243; theme_builder_area=\u00bbpost_content\u00bb][et_pb_blog _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb theme_builder_area=\u00bbpost_content\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;][\/et_pb_blog][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbRelated Services\u00bb _builder_version=\u00bb4.16&#8243; background_color=\u00bb#f7f7f7&#8243; da_disable_devices=\u00bboff|off|off\u00bb global_colors_info=\u00bb{}\u00bb da_is_popup=\u00bboff\u00bb da_exit_intent=\u00bboff\u00bb da_has_close=\u00bbon\u00bb da_alt_close=\u00bboff\u00bb da_dark_close=\u00bboff\u00bb da_not_modal=\u00bbon\u00bb da_is_singular=\u00bboff\u00bb da_with_loader=\u00bboff\u00bb da_has_shadow=\u00bbon\u00bb][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; use_custom_gutter=\u00bbon\u00bb _builder_version=\u00bb4.22.1&#8243; custom_margin=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_slider _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_slide _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb background_enable_color=\u00bboff\u00bb background_image=\u00bbhttps:\/\/cajapopular.gov.ar\/wp-content\/uploads\/2024\/11\/Screenshot_3-e1730992782804.png\u00bb background_enable_image=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb sticky_transition=\u00bbon\u00bb][\/et_pb_slide][et_pb_slide _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb background_image=\u00bbhttps:\/\/cajapopular.gov.ar\/wp-content\/uploads\/2024\/11\/Screenshot_1-e1730992242792.png\u00bb background_enable_image=\u00bbon\u00bb custom_padding=\u00bb340px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb sticky_transition=\u00bbon\u00bb][\/et_pb_slide][\/et_pb_slider][et_pb_cta button_url=\u00bb#\u00bb _builder_version=\u00bb4.22.1&#8243; header_font=\u00bbArimo|700|||||||\u00bb header_font_size=\u00bb16px\u00bb header_line_height=\u00bb1.2em\u00bb body_font=\u00bb||||||||\u00bb body_font_size=\u00bb15px\u00bb body_line_height=\u00bb1.8em\u00bb background_color=\u00bb#eaeaea\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb11px\u00bb button_text_color=\u00bb#666666&#8243; button_border_color=\u00bb#dfdfdf\u00bb button_border_radius=\u00bb0px\u00bb button_letter_spacing=\u00bb4px\u00bb button_font=\u00bbRubik|700||on|||||\u00bb button_icon=\u00bb&#x24;||divi||400&#8243; text_orientation=\u00bbleft\u00bb background_layout=\u00bblight\u00bb custom_padding=\u00bb35px|35px|35px|35px|true|true\u00bb border_width_all=\u00bb1px\u00bb border_color_all=\u00bbrgba(0,0,0,0.12)\u00bb button_letter_spacing_hover=\u00bb4px\u00bb button_bg_color_hover=\u00bbrgba(0,0,0,0)\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bbon\u00bb button_letter_spacing__hover=\u00bb4px\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bbon\u00bb button_bg_color__hover=\u00bbrgba(0,0,0,0)\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb]<\/p>\n<p>Desde Caja Popular de Ahorros brindamos <strong>capacitaciones sobre accidentolog\u00eda para ni\u00f1os y ni\u00f1as de 6\u00b0 grado<\/strong> de escuelas primarias dependientes del Ministerio de Educaci\u00f3n de la Provincia, en el marco de nuestro seguro escolar <strong>Clase Protegida.<\/strong><\/p>\n<p>[\/et_pb_cta][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_slider _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_slide _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb background_enable_color=\u00bboff\u00bb background_image=\u00bbhttps:\/\/cajapopular.gov.ar\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-03-08-at-13.41.16-scaled.jpeg\u00bb background_enable_image=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb sticky_transition=\u00bbon\u00bb][\/et_pb_slide][et_pb_slide _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb background_enable_color=\u00bboff\u00bb background_image=\u00bbhttps:\/\/cajapopular.gov.ar\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-03-08-at-13.52.47-scaled.jpeg\u00bb background_enable_image=\u00bbon\u00bb background_position=\u00bbtop_right\u00bb custom_padding=\u00bb340px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb sticky_transition=\u00bbon\u00bb][\/et_pb_slide][\/et_pb_slider][et_pb_cta button_url=\u00bb#\u00bb _builder_version=\u00bb4.22.1&#8243; header_font=\u00bbArimo|700|||||||\u00bb header_font_size=\u00bb16px\u00bb header_line_height=\u00bb1.2em\u00bb body_font=\u00bb||||||||\u00bb body_font_size=\u00bb15px\u00bb body_line_height=\u00bb1.8em\u00bb background_color=\u00bb#eaeaea\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb11px\u00bb button_text_color=\u00bb#666666&#8243; button_border_color=\u00bb#dfdfdf\u00bb button_border_radius=\u00bb0px\u00bb button_letter_spacing=\u00bb4px\u00bb button_font=\u00bbRubik|700||on|||||\u00bb button_icon=\u00bb&#x24;||divi||400&#8243; text_orientation=\u00bbleft\u00bb background_layout=\u00bblight\u00bb custom_padding=\u00bb35px|35px|35px|35px|true|true\u00bb border_width_all=\u00bb1px\u00bb border_color_all=\u00bbrgba(0,0,0,0.12)\u00bb button_letter_spacing_hover=\u00bb4px\u00bb button_bg_color_hover=\u00bbrgba(0,0,0,0)\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bbon\u00bb button_letter_spacing__hover=\u00bb4px\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bbon\u00bb button_bg_color__hover=\u00bbrgba(0,0,0,0)\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb]<\/p>\n<p>Caja Popular de Ahorros realiz\u00f3 la puesta en revalorizaci\u00f3n de su <strong>Sucursal en la provincia de C\u00f3rdoba.<\/strong> Con una fachada totalmente renovada y una nueva ubicaci\u00f3n, en Avenida Col\u00f3n 335.<\/p>\n<p>[\/et_pb_cta][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image title_text=\u00bb2&#8243; force_fullwidth=\u00bbon\u00bb align_tablet=\u00bbcenter\u00bb align_phone=\u00bbcenter\u00bb align_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.22.1&#8243; background_image=\u00bbhttps:\/\/cajapopular.gov.ar\/wp-content\/uploads\/2024\/08\/2.jpeg\u00bb custom_margin=\u00bb||30px|\u00bb custom_padding=\u00bb400px||||false|false\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_vertical=\u00bb30px\u00bb box_shadow_blur=\u00bb65px\u00bb box_shadow_spread=\u00bb-30px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.35)\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_cta button_url=\u00bb#\u00bb _builder_version=\u00bb4.22.1&#8243; header_font=\u00bbArimo|700|||||||\u00bb header_font_size=\u00bb16px\u00bb header_line_height=\u00bb1.2em\u00bb body_font=\u00bb||||||||\u00bb body_font_size=\u00bb15px\u00bb body_line_height=\u00bb1.8em\u00bb background_color=\u00bb#eaeaea\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb11px\u00bb button_text_color=\u00bb#666666&#8243; button_border_color=\u00bb#dfdfdf\u00bb button_border_radius=\u00bb0px\u00bb button_letter_spacing=\u00bb4px\u00bb button_font=\u00bbRubik|700||on|||||\u00bb button_icon=\u00bb&#x24;||divi||400&#8243; text_orientation=\u00bbleft\u00bb background_layout=\u00bblight\u00bb custom_padding=\u00bb35px|35px|35px|35px|true|true\u00bb border_width_all=\u00bb1px\u00bb border_color_all=\u00bbrgba(0,0,0,0.12)\u00bb button_letter_spacing_hover=\u00bb4px\u00bb button_bg_color_hover=\u00bbrgba(0,0,0,0)\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bbon\u00bb button_letter_spacing__hover=\u00bb4px\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bbon\u00bb button_bg_color__hover=\u00bbrgba(0,0,0,0)\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb]<\/p>\n<p>En Julio del 2024 lanzamos <strong>FECPA<\/strong> (Fundaci\u00f3n de Ense\u00f1anza Superior de la Caja Popular de Ahorros) en busca de contribuir a la inclusi\u00f3n y formaci\u00f3n de una sociedad m\u00e1s justa, brindando herramientas y recursos para el desarrollo laboral.<\/p>\n<p>[\/et_pb_cta][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb da_disable_devices=\u00bboff|off|off\u00bb global_colors_info=\u00bb{}\u00bb da_is_popup=\u00bboff\u00bb da_exit_intent=\u00bboff\u00bb da_has_close=\u00bbon\u00bb da_alt_close=\u00bboff\u00bb da_dark_close=\u00bboff\u00bb da_not_modal=\u00bbon\u00bb da_is_singular=\u00bboff\u00bb da_with_loader=\u00bboff\u00bb da_has_shadow=\u00bbon\u00bb][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb1&#8243; specialty=\u00bbon\u00bb background_color_1=\u00bb#007d83&#8243; padding_top_1=\u00bb80px\u00bb padding_right_1=\u00bb6vw\u00bb padding_bottom_1=\u00bb80px\u00bb padding_left_1=\u00bb6vw\u00bb padding_top_bottom_link_1=\u00bbtrue\u00bb padding_left_right_link_1=\u00bbtrue\u00bb padding_1_tablet=\u00bb|10%||10%||true\u00bb padding_1_phone=\u00bb\u00bb padding_1_last_edited=\u00bbon|phone\u00bb admin_label=\u00bbFooter Section\u00bb module_class=\u00bb et_pb_specialty_fullwidth\u00bb _builder_version=\u00bb4.22.1&#8243; inner_width=\u00bb100%\u00bb inner_width_tablet=\u00bb100%\u00bb inner_width_phone=\u00bb100%\u00bb inner_width_last_edited=\u00bbon|desktop\u00bb inner_max_width=\u00bb100%\u00bb inner_max_width_tablet=\u00bb100%\u00bb inner_max_width_phone=\u00bb100%\u00bb inner_max_width_last_edited=\u00bbon|desktop\u00bb custom_padding=\u00bb0px||0px||true\u00bb da_disable_devices=\u00bboff|off|off\u00bb make_fullwidth=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb da_is_popup=\u00bboff\u00bb da_exit_intent=\u00bboff\u00bb da_has_close=\u00bbon\u00bb da_alt_close=\u00bboff\u00bb da_dark_close=\u00bboff\u00bb da_not_modal=\u00bbon\u00bb da_is_singular=\u00bboff\u00bb da_with_loader=\u00bboff\u00bb da_has_shadow=\u00bbon\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; background_color=\u00bb#ffb400&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb padding_tablet=\u00bb|10%||10%||true\u00bb padding_last_edited=\u00bbon|phone\u00bb custom_padding__hover=\u00bb|||\u00bb padding_phone=\u00bb|10%||10%||true\u00bb][et_pb_text _builder_version=\u00bb4.22.1&#8243; text_font=\u00bb||||||||\u00bb header_font=\u00bb||||||||\u00bb header_2_font=\u00bbRoboto|700|||||||\u00bb header_2_text_color=\u00bb#ffffff\u00bb header_2_font_size=\u00bb42px\u00bb header_2_line_height=\u00bb1.2em\u00bb custom_margin=\u00bb|||\u00bb custom_padding=\u00bb|||\u00bb header_2_font_size_tablet=\u00bb\u00bb header_2_font_size_phone=\u00bb36px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Contacto<\/h2>\n<p>[\/et_pb_text][et_pb_divider color=\u00bb#FFFFFF\u00bb divider_position=\u00bbcenter\u00bb divider_weight=\u00bb5px\u00bb _builder_version=\u00bb4.22.1&#8243; max_width=\u00bb50px\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][et_pb_contact_form captcha=\u00bboff\u00bb email=\u00bbcontacto@cajapopular.gov.ar\u00bb success_message=\u00bbGracias por comunicarte con nosotros. Te responderemos a la brevedad\u00bb submit_button_text=\u00bbEnviar\u00bb module_id=\u00bbet_pb_contact_form_0&#8243; _builder_version=\u00bb4.22.1&#8243; form_field_background_color=\u00bb#ffffff\u00bb title_font=\u00bb||||||||\u00bb form_field_font=\u00bb||||||||\u00bb form_field_font_size=\u00bb14px\u00bb form_field_line_height=\u00bb1.8em\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb14px\u00bb button_text_color=\u00bb#ffffff\u00bb button_border_width=\u00bb2px\u00bb button_border_radius=\u00bb5px\u00bb button_letter_spacing=\u00bb3px\u00bb button_font=\u00bbRoboto|700||on|||||\u00bb button_icon=\u00bb&#x24;||divi||400&#8243; custom_margin=\u00bb30px||30px||true\u00bb custom_margin_last_edited=\u00bboff|desktop\u00bb form_background_color=\u00bb#ffffff\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_contact_field field_id=\u00bbNombre\u00bb field_title=\u00bbNombre\u00bb _builder_version=\u00bb4.22.1&#8243; global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00bbEmail\u00bb field_title=\u00bbEmail\u00bb field_type=\u00bbemail\u00bb _builder_version=\u00bb4.22.1&#8243; global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00bbMessage\u00bb field_title=\u00bbMensaje\u00bb field_type=\u00bbtext\u00bb fullwidth_field=\u00bbon\u00bb _builder_version=\u00bb4.22.1&#8243; global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_contact_field][\/et_pb_contact_form][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; specialty_columns=\u00bb2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_row_inner _builder_version=\u00bb4.16&#8243; background_color=\u00bb#2a2a2a\u00bb custom_margin=\u00bb|||\u00bb custom_padding=\u00bb0px||0px||true\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbtop\u00bb animation_intensity_slide=\u00bb10%\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column_inner saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_social_media_follow _builder_version=\u00bb4.22.1&#8243; text_orientation=\u00bbcenter\u00bb custom_padding=\u00bb40px||40px||true\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_social_media_follow_network social_network=\u00bbfacebook\u00bb url=\u00bbhttps:\/\/www.facebook.com\/cajapopular.tuc\/?locale=es_LA\u00bb _builder_version=\u00bb4.22.1&#8243; custom_padding=\u00bb|10px||10px||true\u00bb global_colors_info=\u00bb{}\u00bb follow_button=\u00bboff\u00bb url_new_window=\u00bbon\u00bb]facebook[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=\u00bbtwitter\u00bb url=\u00bbhttps:\/\/x.com\/CajaPopularTuc\u00bb _builder_version=\u00bb4.22.1&#8243; custom_padding=\u00bb|10px||10px||true\u00bb global_colors_info=\u00bb{}\u00bb follow_button=\u00bboff\u00bb url_new_window=\u00bbon\u00bb]twitter[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=\u00bbinstagram\u00bb url=\u00bbhttps:\/\/www.instagram.com\/cajapopular.tuc\/\u00bb _builder_version=\u00bb4.22.1&#8243; background_color=\u00bbRGBA(255,255,255,0)\u00bb background_enable_color=\u00bbon\u00bb custom_padding=\u00bb|10px||10px||true\u00bb global_colors_info=\u00bb{}\u00bb follow_button=\u00bboff\u00bb url_new_window=\u00bbon\u00bb]instagram[\/et_pb_social_media_follow_network][\/et_pb_social_media_follow][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner custom_padding_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb80px|6vw|80px|6vw|true|true\u00bb custom_padding_tablet=\u00bb|3vw||3vw||true\u00bb custom_padding_phone=\u00bb\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column_inner saved_specialty_column_type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbSan Mart\u00edn 469 y 25 de Mayo 149 \u2013 S. M. de Tucum\u00e1n \u2013 Tucum\u00e1n \u2013 Argentina\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe081;||divi||400&#8243; icon_color=\u00bb#666666&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb content_max_width=\u00bb1100px\u00bb _builder_version=\u00bb4.22.1&#8243; header_font=\u00bbRoboto||||||||\u00bb header_text_color=\u00bb#606060&#8243; header_font_size=\u00bb16px\u00bb header_line_height=\u00bb1.2em\u00bb body_font=\u00bb||||||||\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb||20px|\u00bb animation=\u00bboff\u00bb icon_font_size=\u00bb18px\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bb+54 381 450-7100&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#666666&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb content_max_width=\u00bb1100px\u00bb _builder_version=\u00bb4.22.1&#8243; header_font=\u00bbRoboto||||||||\u00bb header_text_color=\u00bb#606060&#8243; header_font_size=\u00bb16px\u00bb header_line_height=\u00bb1.2em\u00bb body_font=\u00bb||||||||\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb||20px|\u00bb animation=\u00bboff\u00bb icon_font_size=\u00bb18px\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbcontacto@cajapopular.gov.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#666666&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb content_max_width=\u00bb1100px\u00bb _builder_version=\u00bb4.22.1&#8243; header_font=\u00bbRoboto||||||||\u00bb header_text_color=\u00bb#606060&#8243; header_font_size=\u00bb16px\u00bb header_line_height=\u00bb1.2em\u00bb body_font=\u00bb||||||||\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb||20px|\u00bb animation=\u00bboff\u00bb icon_font_size=\u00bb18px\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbDe lunes a viernes de 8:00 a 14:00 hs.\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe06b;||divi||400&#8243; icon_color=\u00bb#666666&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb content_max_width=\u00bb1100px\u00bb _builder_version=\u00bb4.22.1&#8243; header_font=\u00bbRoboto||||||||\u00bb header_text_color=\u00bb#606060&#8243; header_font_size=\u00bb16px\u00bb header_line_height=\u00bb1.2em\u00bb body_font=\u00bb||||||||\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb||20px|\u00bb animation=\u00bboff\u00bb icon_font_size=\u00bb18px\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NoticiasCaja Popular de Ahorros concret\u00f3 la revalorizaci\u00f3n de su sucursal en Taf\u00ed del Valle, trasladandola a una nueva ubicaci\u00f3n, en Av Belgrano 175 L101, Galer\u00eda Inti del Taf\u00ed; en el coraz\u00f3n de una de las villas veraniegas por excelencia en nuestra provincia. Con una fachada totalmente renovada, en esta sucursal se podr\u00e1n realizar tr\u00e1mites relacionados [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-912","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.cajapopular.gov.ar\/index.php\/wp-json\/wp\/v2\/pages\/912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cajapopular.gov.ar\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.cajapopular.gov.ar\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.cajapopular.gov.ar\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cajapopular.gov.ar\/index.php\/wp-json\/wp\/v2\/comments?post=912"}],"version-history":[{"count":88,"href":"https:\/\/www.cajapopular.gov.ar\/index.php\/wp-json\/wp\/v2\/pages\/912\/revisions"}],"predecessor-version":[{"id":5415,"href":"https:\/\/www.cajapopular.gov.ar\/index.php\/wp-json\/wp\/v2\/pages\/912\/revisions\/5415"}],"wp:attachment":[{"href":"https:\/\/www.cajapopular.gov.ar\/index.php\/wp-json\/wp\/v2\/media?parent=912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}